{"id":3586,"date":"2020-09-26T00:24:39","date_gmt":"2020-09-26T00:24:39","guid":{"rendered":"http:\/\/www.surcolor.com\/www\/?p=3586"},"modified":"2020-09-22T03:49:40","modified_gmt":"2020-09-22T03:49:40","slug":"peur-de-la-rencontre-amoureuse","status":"publish","type":"post","link":"http:\/\/www.surcolor.com\/www\/2020\/09\/26\/peur-de-la-rencontre-amoureuse\/","title":{"rendered":"Peur De La Rencontre Amoureuse"},"content":{"rendered":"<p> Romain Sardou-Festival du livre de Nice. Le 14 juin 2014 JLPPA Bestimage L\u00e0, TU TE DEMANDES QUAND M\u0206ME COMMENT JAI FAIT POUR MATTIRER UN CONJOINT PARFAIT POUR MOI? Quand on vit dans le besoin \u00e0 lautre, alors on a peur de perdre cette chose essentielle et ainsi r\u00e9agir en cherchant \u00e0 retenir lautre par le contr\u00f4le, la peur, lob\u00e9issance, les ordres, les conditions et les condamnations. Bonjour, je traverse un terrible moment, ma vie professionnelle est r\u00e9duite \u00e0 n\u00e9ant et du coup tous mes insucc\u00e9s remontent \u00e0 la surface.. Je suis seule \u00e0 43 ans, je nai ni enfant ni ami, je ne veux plus plaire, je ne sors plus, jai peur du regard des hommes, il y a m\u00eame des moments ou le formation \u00e0 la prise de parole en public, ou bien en sinscrivant \u00e0 un bon Je suis tomb\u00e9 par hasard sur cette page web. Je cherchais lauteur portoricain dune citation c\u00e9l\u00e8bre Bref. Parent.querySelector.cool-tag-cloud-load-more.classList.togglecool-tag-cloud-active; <img decoding=\"async\" src=\"http:\/\/cdn1-doctissimo.ladmedia.fr\/var\/doctissimo\/storage\/images\/fr\/www\/psychologie\/rencontre-amoureuse\/trac-amour\/176090-2-fre-FR\/trac-amour.jpg\" alt=\"peur de la rencontre amoureuse\" align=\"center\"> Il y a tout dabord, le plus souvent, une anticipation pers\u00e9cutoire, autour des cons\u00e9quences de cette d\u00e9cision pour le quittant et pour le quitt\u00e9. Dans leur t\u00eate se cr\u00e9ent diff\u00e9rents sc\u00e9narios dans lesquels ils imaginent ce qui pourrait se passer chez lun et chez lautre, en relation directe avec la d\u00e9cision de partir, avec parfois le poids dune r\u00e9pression imaginaire toujours \u00e0 laff\u00fbt. Lire plus : http:www.relationplus.orgBlog12-principes-avoir-relation-amoureuse-durable.html LArt daimer, du grand po\u00e8te romain Ovide, est un trait\u00e9 de la s\u00e9duction o\u00f9 lauteur donne davis\u00e9s conseils aux jeunes galants sur la fa\u00e7on de sy prendre pour s\u00e9duire les femmes. Nous sommes \u00e0 Rome vers lan 0, dans une soci\u00e9t\u00e9 patriarcale et militaire. Aussi, les propos dOvide fleurent bon le machisme. Le point de vue est celui du conqu\u00e9rant, voire du pr\u00e9dateur, il faut savoir prendre une femme de force : Quand la force triomphe dune belle, cest quelle la bien voulu. Mais Ovide, et cela est plus actuel, pense que si le but ultime de la s\u00e9duction est dacc\u00e9der au plaisir de lhomme, il suppose aussi celui de la belle. La femme doit \u00eatre conquise mais aussi respect\u00e9e sois aimable et tu seras aim\u00e9. <img decoding=\"async\" src=\"http:\/\/resize-doctissimo.ladmedia.fr\/r\/1010,forcex\/img\/var\/doctissimo\/storage\/images\/fr\/www\/psychologie\/diaporamas\/philophobie-peur-de-l-amour\/cette-peur-s-appelle-la-philophobie\/2903063-1-fre-FR\/Cette-peur-s-appelle-la-philophobie.jpg\" alt=\"peur de la rencontre amoureuse\" align=\"center\"> Retrouvez le meilleur de T\u00e9l\u00e9rama avec nos quatre newsletters : La Quotidienne, T\u00e9l\u00e9rama Sortir Grand Paris, T\u00e9l\u00e9rama Soir\u00e9e abonn\u00e9 et T\u00e9l\u00e9rama Week-end abonn\u00e9 Nos applis mobile rassurer quoique je fasse pour lui t\u00e9moigner de la profondeur de mes Couple : 11 raisons \u00e9tonnantes qui expliquent lattirance  Lamour, le d\u00e9sir, la trahison, Les Liaisons dangereuses de Pierre Choderlos de Laclos met en sc\u00e8ne des personnages qui savent, ou qui d\u00e9couvrent, que..  normal daspirer \u00e0 faire la rencontre la plus \u00e9panouissante possible sur le <img decoding=\"async\" src=\"http:\/\/www.salama-mag.com\/salamamag\/wp-content\/uploads\/2017\/02\/drague.jpg\" alt=\"peur de la rencontre amoureuse\" align=\"right\"> Cela signifie quil y a un Don dun c\u00f4t\u00e9 de sa personne, et un Don de lautre. Personne ne doit utiliser \u00e0 son profit ce Don, car cela risquerait d\u00e9puiser ou de rendre malheureux autrui. Nous avons toujours les cl\u00e9s en mains pour construire notre avenir. \u00c0 nous de nous faire du bien Vous ne devez pas vous adapter aux attentes de lautre, mais \u00e9coutez vos envies et votre besoin.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>peur de la rencontre amoureuse<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"http:\/\/www.surcolor.com\/www\/wp-json\/wp\/v2\/posts\/3586"}],"collection":[{"href":"http:\/\/www.surcolor.com\/www\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.surcolor.com\/www\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.surcolor.com\/www\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.surcolor.com\/www\/wp-json\/wp\/v2\/comments?post=3586"}],"version-history":[{"count":1,"href":"http:\/\/www.surcolor.com\/www\/wp-json\/wp\/v2\/posts\/3586\/revisions"}],"predecessor-version":[{"id":3587,"href":"http:\/\/www.surcolor.com\/www\/wp-json\/wp\/v2\/posts\/3586\/revisions\/3587"}],"wp:attachment":[{"href":"http:\/\/www.surcolor.com\/www\/wp-json\/wp\/v2\/media?parent=3586"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.surcolor.com\/www\/wp-json\/wp\/v2\/categories?post=3586"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.surcolor.com\/www\/wp-json\/wp\/v2\/tags?post=3586"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}